{"id":2762,"date":"2024-05-04T20:25:46","date_gmt":"2024-05-05T01:25:46","guid":{"rendered":"https:\/\/elcuyabranpost.com\/?p=2762"},"modified":"2024-05-06T12:42:15","modified_gmt":"2024-05-06T17:42:15","slug":"hay-como-lidiar-con-la-explosion-exponencial-de-la-moto-en-el-quindio","status":"publish","type":"post","link":"https:\/\/elcuyabranpost.com\/index.php\/2024\/05\/04\/hay-como-lidiar-con-la-explosion-exponencial-de-la-moto-en-el-quindio\/","title":{"rendered":"\u00bfHay c\u00f3mo lidiar con la explosi\u00f3n exponencial de la moto en el Quind\u00edo?"},"content":{"rendered":"\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">Bajo una noche que empieza a caer sobre la ciudad de Armenia, en medio de un tranc\u00f3n (de esos que se han vuelto habituales en una urbe con pocas v\u00edas y cada vez m\u00e1s veh\u00edculos), una luz serpentea por entre las luminarias est\u00e1ticas de los autom\u00f3viles que avanzan a paso de procesi\u00f3n; una luz que anuncia a un motociclista acerc\u00e1ndose. Al verlo por el retrovisor, Sara repliega el espejo lateral de su camioneta. \u201cA esos hijueputas no les importa arrancarle el espejo a uno y volarse. A un t\u00edo le rayaron el carro la otra vez que lo choc\u00f3 uno por detr\u00e1s y vaya h\u00e1gale pagar\u2026 era un culicagado como de 18 a\u00f1os\u201d.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">La situaci\u00f3n no solo la viven los pasajeros. El pasado viernes en pleno parque Sucre un motociclista cruz\u00f3 la carrera 14 por la calle 13, y estuvo a escasos instantes de atropellar un peat\u00f3n. Vol\u00f3 el zapato del joven casi arrollado y el conductor, reaccionando como mejor pudo para evitar el accidente, fren\u00f3 en seco sobre el suelo mojado por la lluvia y termin\u00f3 en el piso, sin mayores contratiempos aparte de rasparse un brazo. Sin embargo, no todos los incidentes terminan as\u00ed. La imprudencia de algunas personas con acceso a este tipo de veh\u00edculo y la temeridad con la que se enfrentan al tr\u00e1fico, se han convertido en un problema de salud p\u00fablica en el Quind\u00edo.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">No nos parece exagerado. Las cifras as\u00ed lo se\u00f1alan, y no es un fen\u00f3meno exclusivo de la regi\u00f3n: De acuerdo con las cifras de la Agencia de Seguridad Vial a trav\u00e9s de su Observatorio Nacional de Seguridad Vial, las muertes en toda Colombia asociadas a este modo de transporte, solo en el mes de marzo de 2024, ascendieron a 181: 134 ocupando el asiento de conductor y 47 como pasajeros; mientras que en el Quind\u00edo se reportaron 13 fallecidos: 10 conductores y 3 pasajeros.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/2-1024x576.png?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-2763\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/2.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/2.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/2.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/2.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/2.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>Un crecimiento absurdo en el parque automotor<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">No es un secreto: comprar una moto en Colombia es f\u00e1cil, r\u00e1pido y econ\u00f3mico. Es la mejor alternativa para una gran parte de la poblaci\u00f3n que necesita alternativas de transporte para trabajar o incluso para movilizarse; esa es la clave de su \u00e9xito en econom\u00edas en crecimiento y comunidades con una capacidad adquisitiva limitada. No pagan peajes, si su cilindraje es inferior a los 125 cent\u00edmetros c\u00fabicos no pagan impuesto Vehicular, entre varias ocupan lo que ocupa un carro en parqueo y tanto los repuestos como el costo de su combustible es significativamente menor que el de otro tipo de veh\u00edculos.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">La moto no solo se comercializa en el comercio formal. El mercado del usado ha encontrado incluso en redes sociales, un canal de promoci\u00f3n muy efectivo; es solo echar una mirada r\u00e1pida al Marketplace de Facebook, para evidenciar lo f\u00e1cil que es comprar una. E incluso se sabe de lugares que venden motocicletas sin papeles e integradas de partes de otras robadas, o a\u00fan m\u00e1s, que las alquilan. Si de por s\u00ed las cifras eran altas, con la migraci\u00f3n masiva de poblaci\u00f3n venezolana al resto del continente termino de disparar las estad\u00edsticas: las plataformas de domicilios suelen ser algunas de las mejores opciones para un grupo poblacional que tuvo que reiniciar de cero. <\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">\u201cTenemos que prestar especial atenci\u00f3n al fen\u00f3meno, porque hay un incremento indiscriminado\u201d, se\u00f1ala Uriel Enoc Ortiz D\u00edaz, director del Instituto Departamental de Tr\u00e1nsito del Quind\u00edo \u2013 IDTQ, \u201cen abril, por ejemplo, se registraron en la entidad m\u00e1s de 650 motos nuevas, frente a 29 autom\u00f3viles\u201d. La diferencia entre ambos describe la desproporci\u00f3n. Pero este no es el dato que le preocupa: \u201cHay que tener en cuenta que el 85% de los accidentes involucran a una motocicleta\u201d.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/4-1024x576.png?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-2769\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/4.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/4.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/4.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/4.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/4.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>Un golpe al capital humano del Quind\u00edo<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">A esta cifra, ofrecida por el director del IDTQ se le suma otra, igual de preocupante: los accidentes de tr\u00e1nsito en los que se ven involucrados motociclistas se ubican hoy en d\u00eda como \u201cla tercera causa de muerte en el departamento por encima de los infartos card\u00edacos y los accidentes cerebro vasculares, con una tasa del 25,6% por cada 100.000 habitantes\u201d, explica el secretario de Salud del departamento, Carlos Alberto G\u00f3mez Chac\u00f3n.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">Normalmente, a\u00f1ade, la siniestralidad es m\u00e1s alta en hombres que en mujeres. Pero adem\u00e1s, se presenta con mayor frecuencia en menores de 25 a\u00f1os, es decir, personas en plena edad productiva. \u201cAc\u00e1 solo estamos mirando cifras de mortalidad, pero hay otros \u00edndices que deber\u00edamos medir, por ejemplo, los a\u00f1os de vida perdidos por una discapacidad derivada de un accidente a una persona que no fallezca, o cu\u00e1nto tiempo se gasta en recuperar su vida normal y la posibilidad de reincorporarse a sus actividades normales\u201d.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">Y son esos a\u00f1os cesantes, o la p\u00e9rdida de capacidades debido a una discapacidad, las que junto con las muertes, parece pintar un panorama preocupante porque est\u00e1n concentradas en j\u00f3venes, que en una sociedad como la colombiana, representa la mano de obra y el talento humano para potenciarse y ser competitiva.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/Chacon-1024x576.png?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-2788\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/Chacon.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/Chacon.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/Chacon.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/Chacon.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/Chacon.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>La salud y el aseguramiento se desangran lentamente<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">En diciembre de 2022, como una de las primeras acciones como mandatario del pa\u00eds, el Presidente de la Rep\u00fablica, Gustavo Petro Urrego <a href=\"https:\/\/petro.presidencia.gov.co\/prensa\/Paginas\/Presidente-Petro-firmo-decreto-para-reducir-tarifas-del-SOAT-hasta-en-un-50-221217.aspx\" title=\"\">redujo en un 50% el valor del Seguro Obligatorio de Accidentes de Tr\u00e1nsito \u2013 SOAT<\/a>. La medida amortigu\u00f3 el impacto en el bolsillo de la poblaci\u00f3n con m\u00e1s necesidades, a la vez que incentivaba la venta, particularmente de cilindrajes de entre 100 y 200 cc, quedaron cubiertas con este beneficio.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">De acuerdo con el decreto 2497 de 2022, el impacto generado por estas medidas, se financia \u201ccon transferencias que el Presupuesto General de la Naci\u00f3n apropiar\u00e1 del Sistema General de Seguridad Social en Salud a cargo de la Administradora de los Recursos del Sistema General de Seguridad Social en Salud (ADRESS), de acuerdo con las disponibilidades presupuestales\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/La-tecnico-mecanica-del-fenomeno-de-la-moto-1024x576.png?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-2789\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/La-tecnico-mecanica-del-fenomeno-de-la-moto.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/La-tecnico-mecanica-del-fenomeno-de-la-moto.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/La-tecnico-mecanica-del-fenomeno-de-la-moto.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/La-tecnico-mecanica-del-fenomeno-de-la-moto.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/La-tecnico-mecanica-del-fenomeno-de-la-moto.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">Justamente este fondo es el que est\u00e1 recibiendo gran parte del golpe. De acuerdo con el secretario de Salud del Quind\u00edo, Carlos Alberto G\u00f3mez Chac\u00f3n, gran parte de la atenci\u00f3n m\u00e9dica que se le brinda a los pacientes de accidentes termina siendo pagada por esta instancia.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">\u201cDe acuerdo a cifras del Registro \u00danico Nacional de Tr\u00e1nsito \u2013 RUNT, un 61% de las motos en el pa\u00eds circular\u00edan sin Seguro Obligatorio de Accidentes de Tr\u00e1nsito \u2013 SOAT, un instrumento financiero que cubre los gastos m\u00e9dicos originados por un evento de este tipo. Cuando las atenciones m\u00e9dicas provistas no est\u00e1n debidamente cubiertas por un SOAT las terminan pagando las Instituciones Prestadoras de Salud, con cargo a la Adress, que es la que les devuelve esos recursos a trav\u00e9s de un proceso que se tarda m\u00e1s de lo que desear\u00edamos\u201d, agrega G\u00f3mez Chac\u00f3n.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/6-1024x576.png?resize=1920%2C1080&#038;ssl=1\" alt=\"\" class=\"wp-image-2767\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/6.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/6.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/6.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/6.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/6.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>Tomando el toro por los cuernos<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">El panorama es complejo pero desde diferentes frentes se trabaja, habiendo logrado ya resultados importantes en algunos casos, y dejando altas expectativas en otros. Desde la Agencia Nacional de Seguridad Vial, por ejemplo, <a href=\"https:\/\/ansv.gov.co\/es\/prensa-comunicados\/10868\" title=\"\">se reporta una disminuci\u00f3n en 2023 de las fatalidades por siniestros viales, en comparaci\u00f3n con 2022<\/a>. Y el Quind\u00edo hace parte del podio.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\">\u201c(\u2026) al terminar el a\u00f1o se evidenci\u00f3 que 16 departamentos y 17 ciudades capitales lograron salvar vidas, con una reducci\u00f3n en las fatalidades por siniestros viales en 2023 comparativamente con 2022. Entre los departamentos se destacaron Boyac\u00e1 y Quind\u00edo con una disminuci\u00f3n en la fatalidad del 13,2% y 19,8% respectivamente, y entre las ciudades Manizales, Armenia y Tunja con una ca\u00edda del 19,2%, 20,6% y 21,2% respectivamente\u201d, reitera el comunicado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/7-1024x576.png?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-2768\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/7.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/7.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/7.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/7.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/7.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">Entre tanto, el aumento en el volumen de los agentes de tr\u00e1nsito en el IDTQ le ha permitido a la entidad una mejor atenci\u00f3n en las v\u00edas a su cargo, al duplicar la planta de personal. Y desde la Alcald\u00eda de Armenia la confianza est\u00e1 depositada en el proyecto de modernizaci\u00f3n de la Secretar\u00eda de Tr\u00e1nsito y Transporte de Armenia \u2013 SETTA. La iniciativa hoy espera concepto favorable de parte del Tribunal Administrativo del Quind\u00edo para arrancar, <a href=\"https:\/\/elcuyabranpost.com\/index.php\/2024\/03\/04\/las-camaras-de-fotomultas-que-quiere-instalar-setta-es-como-firmar-un-cheque-en-blanco\/\" title=\"\">pese a la incertidumbre de su conveniencia para las finanzas de la capital<\/a>, pero es indudable que, independiente a esto, podr\u00eda fortalecer la prevenci\u00f3n y la cultura vial que tanto necesitamos para demostrarnos a nosotros mismos, que somos capaces de soportar las cientos y cientos de motos que parecen aflorar como pasto en una ciudad abarrotada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo una noche que empieza a caer sobre la ciudad de Armenia, en medio de un tranc\u00f3n (de esos que se han vuelto habituales en una urbe con pocas v\u00edas y cada vez m\u00e1s veh\u00edculos), una luz serpentea por entre las luminarias est\u00e1ticas de los autom\u00f3viles que avanzan a paso de procesi\u00f3n; una luz que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16],"tags":[282,281,283,129,280,244],"class_list":["post-2762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elpostreporta","tag-accidentalidad","tag-aseguramiento","tag-idtq","tag-movilidad","tag-salud-publica","tag-setta"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2024\/05\/5.png?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts\/2762"}],"collection":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/comments?post=2762"}],"version-history":[{"count":5,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts\/2762\/revisions"}],"predecessor-version":[{"id":2810,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts\/2762\/revisions\/2810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/media\/2765"}],"wp:attachment":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/media?parent=2762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/categories?post=2762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/tags?post=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}