{"id":4836,"date":"2025-02-12T18:35:03","date_gmt":"2025-02-12T23:35:03","guid":{"rendered":"https:\/\/elcuyabranpost.com\/?p=4836"},"modified":"2025-02-17T17:02:24","modified_gmt":"2025-02-17T22:02:24","slug":"la-muerte-en-el-nevado-una-cadena-de-eventos-desafortunados","status":"publish","type":"post","link":"https:\/\/elcuyabranpost.com\/index.php\/2025\/02\/12\/la-muerte-en-el-nevado-una-cadena-de-eventos-desafortunados\/","title":{"rendered":"La muerte en el nevado. Una cadena de eventos desafortunados"},"content":{"rendered":"\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\"><em>Por: Andr\u00e9s Mej\u00eda &#8211; Sebasti\u00e1n Ruiz &#8211; Miguel \u00c1ngel Mej\u00eda<\/em><\/p>\n\n\n\n<p style=\"font-size:22px\"><br>La mayor\u00eda de las veces, el tomar una decisi\u00f3n por encima de otra no origina diferencias dr\u00e1sticas. Pero en ambientes hostiles, que exigen al cuerpo a rendir en condiciones extremas, una disyuntiva puede sostener o cegar una vida. Tom\u00e1ndose un caf\u00e9 mientras me cuenta su experiencia, a Adri\u00e1n Quintero se le nota en la mirada que su pensamiento vuela a la monta\u00f1a, que regresa sobre sus pasos y trata de identificar qu\u00e9 fue lo que le salv\u00f3 la vida. M\u00e1s a\u00fan cuando hace menos de dos meses, Kevin Bocanegra la perdi\u00f3 en contra de la naturaleza. Ambos comparten en sus historias la misma ruta y la misma afecci\u00f3n, que result\u00f3 mortal para el segundo.<\/p>\n\n\n\n<p style=\"font-size:22px\">El caso del <a href=\"https:\/\/lakalle.bluradio.com\/noticias\/kevin-bocanegra-las-causas-de-la-muerte-del-joven-montanista-en-el-nevado-del-tolima-so35\" title=\"\">monta\u00f1ista fallecido en el nevado del Tolima el pasado 31 de diciembre<\/a> gener\u00f3 muchos titulares. Y rumores que no vienen al caso que vamos a tratar. Porque los comentarios de que el objetivo de la visita al santuario natural involucraba la grabaci\u00f3n de un v\u00eddeo sexual y los se\u00f1alamientos en contra de su novia por el presunto inter\u00e9s de capitalizar el morbo generado para alimentar sus seguidores en cierta p\u00e1gina azul, se quedar\u00e1n en eso, por lo menos en este art\u00edculo.<\/p>\n\n\n\n<p style=\"font-size:22px\">-El a\u00f1o pasado subiste dos veces-, interrumpo en su abstracci\u00f3n a Adri\u00e1n.<\/p>\n\n\n\n<p style=\"font-size:22px\">-S\u00ed. En febrero de 2024, con un grupo de amigos, contratamos una empresa certificada de Salento para que nos guiara al nevado del Tolima porque quer\u00eda celebrar mi cumplea\u00f1os haciendo cumbre. Nos encontramos con los rescatistas en una finca llamada La Playa, que es donde normalmente siempre pernocto. Hicimos en esa ocasi\u00f3n el camino m\u00e1s fuerte, que fue salir de Cocora el 4 de febrero y llegar ese d\u00eda a las 11:00 de la noche. Sal\u00edamos de all\u00ed de madrugada, para que el 5 de febrero estuvi\u00e9ramos en la cumbre, regres\u00e1bamos ese mismo d\u00eda al refugio y de ah\u00ed baj\u00e1bamos a Cocora. La idea era llegar el 6, completando el recorrido en 3 d\u00edas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/6-1.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4842\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/6-1.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/6-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/6-1.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/6-1.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/6-1.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>Adri\u00e1n Quintero, catador de caf\u00e9 de profesi\u00f3n y monta\u00f1ista de afici\u00f3n.<\/em><\/figcaption><\/figure>\n\n\n\n<p style=\"font-size:22px\">\u00bfSuena duro? A m\u00ed se me baj\u00f3 la presi\u00f3n solo escribiendo esa frase. Pero Adri\u00e1n lleva experiencia de sobra en estas lides; su primera cumbre en este paraje fue a los 16 a\u00f1os y hoy tiene 34. Sus frecuentes ascensos los complementa con otra labor que tambi\u00e9n lo apasiona, pero que adem\u00e1s es su sustento: catador de caf\u00e9 de una empresa muy reconocida del sector en el Quind\u00edo. Continua Adri\u00e1n.<\/p>\n\n\n\n<p style=\"font-size:22px\">-Cuando llegamos a la finca, dos personas que iban en el grupo llegaron muy cansadas y se quedaron en el campamento mientras nosotros subimos. Una de ellas, sin embargo, se qued\u00f3 con el deseo de cumplir el sue\u00f1o de conquistar cumbre, y quedamos en una promesa: que volver\u00edamos en su cumplea\u00f1os para subir de una manera m\u00e1s descansada.<\/p>\n\n\n\n<p style=\"font-size:22px\">Eso dio paso a que regresaran ambos el 12 de mayo al nevado. El 13 hicieron caminatas de reconocimiento, un poco tambi\u00e9n para adaptar el organismo. Y esa noche se prepararon para ingresar de nuevo al glacial, en b\u00fasqueda de la cima. El recorrido lo iban a hacer ellos dos y el gu\u00eda contratado. Salieron a la 1:30 de la ma\u00f1ana.<\/p>\n\n\n\n<p style=\"font-size:22px\">-Cuando llev\u00e1bamos m\u00e1s o menos hora y media, empec\u00e9 a sentir algo extra\u00f1o en mi capacidad f\u00edsica\u2026 que no rend\u00eda igual que lo habitual\u2026 pero no ten\u00eda gripa, ni mucosidad, sino una leve tos como cuando algo te pica en la garganta- describe. Unos s\u00edntomas que Kevin Bocanegra debi\u00f3 sentir tambi\u00e9n si se tiene en cuenta que ambos sufrieron del mismo cuadro m\u00e9dico: un edema pulmonar.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/9-1.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4845\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/9-1.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/9-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/9-1.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/9-1.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/9-1.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>Kevin Bocanegra y su novia, Julieth Ordo\u00f1ez: protagonistas tr\u00e1gicos del evento.<\/em><\/figcaption><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>La parte de Kevin<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">Va a ser dif\u00edcil reconstruir la experiencia del desaparecido Kevin Bocanegra, pero nos vamos a basar en la informaci\u00f3n que ha dado su novia Julieth Ordo\u00f1ez (Jois Ram\u00edrez en redes sociales) y que fue juiciosamente <a href=\"https:\/\/www.eltiempo.com\/colombia\/otras-ciudades\/la-agonizante-travesia-por-el-parque-los-nevados-que-termino-con-la-muerte-de-mi-novio-en-pleno-31-de-diciembre-adios-amor-3418604\" title=\"\">rese\u00f1ada por el diario El Tiempo<\/a>. De acuerdo con esta versi\u00f3n, ambos habr\u00edan llegado a Cocora el 28 de diciembre junto con su suegra Lorena Ram\u00edrez, otro grupo de acompa\u00f1antes (no se especifican cu\u00e1ntos) y uno de sus primos \u00d3scar Apolinar, quien operar\u00eda como gu\u00eda. Los problemas empezaron temprano, con un grupo disgregado en medio del recorrido y momentos en los que se perdieron en el camino. No obstante, habr\u00edan llegado a la finca La Primavera cerca de las 8:00 de la noche.<\/p>\n\n\n\n<p style=\"font-size:22px\">Al amanecer decidieron recorrer el paramillo del Quind\u00edo. El d\u00eda anterior, Kevin hab\u00eda presentado s\u00edntomas de gripe, y esa ma\u00f1ana se present\u00f3 fr\u00eda y lluviosa, incluso nevando en la cumbre, lo que los oblig\u00f3 a regresar al refugio para intentarlo al d\u00eda siguiente. En esta segunda jornada tambi\u00e9n se separ\u00f3 el grupo en varios segmentos y el gu\u00eda se loe \u201crecomend\u00f3\u201d a uno de los caminantes que carec\u00eda de los conocimientos necesarios, de acuerdo con la versi\u00f3n. Al regresar a La Primavera, Kevin empez\u00f3 a presentar una sintomatolog\u00eda preocupante que no fue tenida en cuenta: dolor de cuerpo y congesti\u00f3n. Esa noche la pas\u00f3 con tos.<\/p>\n\n\n\n<p style=\"font-size:22px\">Para el m\u00e9dico y columnista de El Cuyabran Post, Sebasti\u00e1n Ruiz, este primer y casi insignificante s\u00edntoma, podr\u00eda haber sido el punto de inflexi\u00f3n entre la vida y la muerte. \u201cPartimos de la premisa que era un hombre de 25 a\u00f1os en unas condiciones atl\u00e9ticas excelentes. A pesar de que iban perdidos y mal orientados, la subida no fue algo abrupto, porque subieron despacio, lo suficiente para afrontar el descenso en la presi\u00f3n barom\u00e9trica sin enfermarse\u201d.<\/p>\n\n\n\n<p style=\"font-size:22px\">-\u00bfPudieron haber influido las condiciones climatol\u00f3gicas con las que se enfrentaron?<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/7-1.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4843\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/7-1.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/7-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/7-1.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/7-1.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/7-1.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">-Pueden haber incubado una infecci\u00f3n, ante lo cual lo ideal es guardar reposo porque uno va a direccionar sus recursos energ\u00e9ticos a eso- concept\u00faa -Entonces si uno se resfr\u00eda hasta cierto punto y la situaci\u00f3n clim\u00e1tica empeora el estado de salud, es una clara se\u00f1al de que la vaina no va a tener el mejor resultado. Parte m\u00e1s de la imprudencia personal, porque la gente se conf\u00eda mucho en que pueden con una \u2018gripita\u2019.<\/p>\n\n\n\n<p style=\"font-size:22px\">Para el tercer d\u00eda, los miembros de la excursi\u00f3n reanudaron la campa\u00f1a a las 7:00 de la ma\u00f1ana, con un peso mayor que el anterior, llevado por los hombres del grupo, ante lo cual Kevin expres\u00f3 que no se sent\u00eda bien. \u00d3scar, el gu\u00eda, desestim\u00f3 la manifestaci\u00f3n, dici\u00e9ndole con tono juguet\u00f3n que \u201cno fuera flojo\u201d. La meta era llegar a Arenales, pero las condiciones del clima y de nuevo la dispersi\u00f3n del grupo (incluso del gu\u00eda que se habr\u00eda quedado atr\u00e1s), los llevaron a armar una carpa en el punto llamado El Calvito. En este punto, Julieth esper\u00f3 varias horas resguard\u00e1ndose de la lluvia, a que llegara su novio con \u00d3scar.<\/p>\n\n\n\n<p style=\"font-size:22px\">El siguiente pasaje es dram\u00e1tico, y lo trascribimos tal y como lo cuenta en El Tiempo: \u201cLlov\u00eda sin parar un segundo, no hab\u00eda forma de que Kevin cogiera calor corporal porque el fr\u00edo era extremo. Ten\u00edamos que descansar hasta las 2 a. m. del 31 de diciembre ya que Oscar hab\u00eda dado la orden de salir a esa hora a la cumbre. Pasamos una noche terrible. Kevin tos\u00eda mucho, se escuchaba muy congestionado, tuvo fiebre y v\u00f3mito. Me dec\u00eda que quer\u00eda irse a casa. Yo lo cubr\u00eda con mi sleeping, mi ropa, mi aislante\u201d. Al momento de partir, Julieth y Kevin acordaron en que ella, que presentaba mejores condiciones, continuara con el grupo para cumplir con uno de los objetivos: que se tomara fotos para publicar en sus redes sociales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/13.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4849\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/13.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/13.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/13.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/13.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/13.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">La expedici\u00f3n procedi\u00f3 a ascender de manera desorganizada, sin un liderazgo, sintiendo que el viento g\u00e9lido les atravesaba los huesos. El mismo gu\u00eda reconoci\u00f3 no poder dar cinco pasos sin sentirse ahogado. Incluso en el descenso, alcanz\u00f3 a desmayarse, cuenta la entrevistada. Cuando regresaron a la carpa donde hab\u00eda quedado Kevin, este le pidi\u00f3 a su primo que activara el seguro que hab\u00edan comprado, pero no hab\u00eda se\u00f1al de celular en el paraje. Justo ah\u00ed, fue cuando Julieth vio a Kevin expulsar \u201cl\u00edquido amarillo por la nariz en una cantidad exagerada\u201d; la manifestaci\u00f3n m\u00e1s clara de que estaba sufriendo un edema pulmonar.<\/p>\n\n\n\n<p style=\"font-size:22px\">-\u00bfC\u00f3mo explicamos un edema, Sebasti\u00e1n?<\/p>\n\n\n\n<p style=\"font-size:22px\">-A ver\u2026 El pulm\u00f3n evolucion\u00f3 como una esponja compuesta de muchas peque\u00f1as bolsitas, hasta donde llega el aire para que se d\u00e9 el intercambio gaseoso entre gases atmosf\u00e9ricos y los l\u00edquidos del sistema circulatorio. Estas bolsitas deben mantener infladas y llenas de aire; si se colapsan o se llenan de algo que no es aire (en la neumon\u00eda puede ser moco o exudado purulento) o l\u00edquido del interior del sistema circulatorio en condiciones donde la presi\u00f3n, afuera del alve\u00f3lo, es inferior a la del interior, aumentando su permeabilidad. En otras palabras, es como empacar algo al vac\u00edo, se comprime todo y le saca lo de adentro.<\/p>\n\n\n\n<p style=\"font-size:22px\">-\u00bfY qu\u00e9 era el l\u00edquido amarillo que expuls\u00f3?<\/p>\n\n\n\n<p style=\"font-size:22px\">-El exudado de los l\u00edquidos propios del organismo que hab\u00edan invadido las bolsitas del pulm\u00f3n. En ese momento ya ten\u00eda invadidos los alve\u00f3los y empez\u00f3 a expulsarlos a trav\u00e9s de la tr\u00e1quea. Es el l\u00edquido que uno tiene por dentro, tanto en el espacio intravascular como afuera, en los tejidos. Ese cuadro uno lo ve en pacientes muy avanzados.<\/p>\n\n\n\n<p style=\"font-size:22px\">Volvamos a la pesadilla. Arriba, en medio del paisaje agreste, incomunicados y con una situaci\u00f3n cr\u00edtica, los excursionistas se toparon con un arriero que iba subiendo y que les consigui\u00f3 un caballo que llegar\u00eda horas despu\u00e9s para evacuarlo. Alcanz\u00f3 a bajar unos metros con \u00e9l en su lomo hasta que, en medio de gritos de desespero, Kevin perdi\u00f3 el conocimiento. Tras horas de descenso, el animal y su pasajero regresaron a La Primavera. Julieth y su madre llegaron despu\u00e9s, guiadas por las huellas del semoviente que lo transport\u00f3. Fue entonces cuando descubrieron la verdad: el cuerpo de Kevin estaba envuelto en unas lonas. Las palabras de la mujer de la finca retumbaron como campanas: \u201cYa no hay nada que hacer\u201d.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/5-2.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4841\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/5-2.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/5-2.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/5-2.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/5-2.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/5-2.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>La parte de Adri\u00e1n<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">Volvamos a Adri\u00e1n. Recorrida cerca de hora y media desde la finca La Playa en direcci\u00f3n a la cumbre del nevado, empez\u00f3 a sentirse sin aire. Conociendo bastantes historias de miedo que empezaban igual en el nevado, supo que mientras m\u00e1s cerca del nivel del mar estuviera, mientras m\u00e1s descendiera, iba a estar m\u00e1s seguro.<\/p>\n\n\n\n<p style=\"font-size:22px\">-En ese momento les dije al rescatista y la persona que iba conmigo que me hab\u00eda enfermado, que no me sent\u00eda en capacidad, que me devolv\u00eda. Ellos se quer\u00edan regresar conmigo, pero como ella no hab\u00eda logrado hacer cumbre la vez pasada, le dije que siguiera con el rescatista y que, como estaba muy cerca y me conoc\u00eda el camino, me pod\u00eda devolver solo. Estaba s\u00faper cerca del refugio, si se tiene en cuenta que la caminata es de 6 o 7 horas.<\/p>\n\n\n\n<p style=\"font-size:22px\">Lo s\u00e9. La decisi\u00f3n suena osada. Pero recuerden que Adri\u00e1n tiene experiencia en este tema, y puntualmente en este paraje. \u201cTengo soroche\u201d, se dijo para calmarse y empez\u00f3 el descenso, mientras las luces de las linternas de sus acompa\u00f1antes se hac\u00edan cada vez m\u00e1s peque\u00f1as en ese inmenso negro en el que el viento aporreaba los frailejones. Sin embargo, Adri\u00e1n not\u00f3 que, con cada paso, le empezaba a faltar m\u00e1s aire. \u00bfAcaso lo estaba reclamando para s\u00ed la monta\u00f1a que tantas veces lo recibi\u00f3?<\/p>\n\n\n\n<p style=\"font-size:22px\">-Empec\u00e9 a controlar muy bien el poco ox\u00edgeno que pod\u00eda obtener y a caminar muy despacio, sin forzar mucho el coraz\u00f3n o los pulmones, hasta que logr\u00e9 llegar al refugio\u2026 lo que me demor\u00e9 hora y media subiendo, me llev\u00f3 4 horas de regreso y en bajada. Sin embargo, la situaci\u00f3n no mejor\u00f3 all\u00ed: Lo primero que hice fue pedirles el favor de que avisaran por radio al gu\u00eda que deb\u00eda evacuar una vez volviera de la cumbre. Pero ese fin de semana hab\u00eda mucho tr\u00e1fico, y le hab\u00edan prestado el equipo a otro gu\u00eda para que acompa\u00f1ara al grupo que llevaba. Estaba incomunicado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/4-2.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4840\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/4-2.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/4-2.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/4-2.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/4-2.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/4-2.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">Adri\u00e1n not\u00f3 que no era capaz de quedarse acostado porque se ahogaba cuando agachaba la cabeza. Tuvo que dormir en una postura particular que le fue recomendada mientras el sol empezaba a asomar por el borde de la cordillera. Cerca de las 10:00 de la ma\u00f1ana, retornaron la cumplea\u00f1era y el gu\u00eda. Mientras este desayunaba algo y se preparaba para doblar su jornada con el deber de llevarlo a Salento, a Adri\u00e1n le midieron la saturaci\u00f3n de ox\u00edgeno en la sangre; estaba entre 52 y 57, cuando el rango normal es de 92 a 97. Estaba a punto de desmayarse. Le aplicaron dexametasona, lo vistieron, lo cubrieron con un poncho, y lo subieron en un caballo. Las fuerzas le daban solo para no desplomarse de su lomo al suelo.<\/p>\n\n\n\n<p style=\"font-size:22px\">Pero el camino no iba a ser f\u00e1cil. La constante lluvia de la noche anterior hac\u00eda riesgoso el paso habitual. Fue entonces cuando el rescatista tom\u00f3 una decisi\u00f3n bastante peligrosa, pero que representaba la \u00fanica soluci\u00f3n: subir unos metros m\u00e1s, en contrav\u00eda de la perentoria necesidad de que su organismo bajara de esa altura a un entorno de mayor presi\u00f3n atmosf\u00e9rica.<\/p>\n\n\n\n<p style=\"font-size:22px\">-Para revertir la situaci\u00f3n tiene que generar presi\u00f3n barom\u00e9trica y la \u00fanica manera es bajando, perder altura- interviene Sebasti\u00e1n. La jugada es b\u00e1sica; mientras m\u00e1s abajo se est\u00e9 m\u00e1s presi\u00f3n externa se genera, evitando que los pulmones se congestionen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/11.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4847\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/11.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/11.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/11.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/11.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/11.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">Adri\u00e1n y su rescatista lo sab\u00edan pero no hab\u00eda de otra: La idea era bordear el paramillo del Quind\u00edo, de camino a Buenos Aires, La Argentina y por \u00faltimo Cocora, donde un amigo personal lo estar\u00eda esperando para llevarlo al hospital del pueblo; all\u00ed ya lo aguardaban, resultado de la activaci\u00f3n de la p\u00f3liza. Ese recorrido agonizante por una infinidad de paisajes que se concatenaban de manera incesante mientras sent\u00eda que su vida se escapaba en un hilo de respiraci\u00f3n, dur\u00f3 de 10:00 de la ma\u00f1ana hasta las 3:00 de la tarde. Pero del hospital de Salento, el paciente no sali\u00f3 hasta las 10:30 de la noche, cuando la doctora estuvo segura de que estuviera estable, luego de una sesi\u00f3n intensa de inhalaciones de salbutamol y medicamentos intravenosos.<\/p>\n\n\n\n<p style=\"font-size:22px\">Ya en Armenia, en los d\u00edas siguientes, Adri\u00e1n fue sujeto de ex\u00e1menes de saturaci\u00f3n de ox\u00edgeno, presiones de gases arteriales, capacidad pulmonar y electrocardiogramas, revelando que no hab\u00eda ning\u00fan problema de ra\u00edz, enfermedad de base o secuela. \u201cLo \u00fanico que no logramos descartar y fue una conjetura, es la posibilidad de que tuviera COVID asintom\u00e1tico, y que al estar en esa altura y forzar el cuerpo, los pulmones no respondieran como deb\u00edan y se hubieran llenado de l\u00edquido\u201d.<\/p>\n\n\n\n<p style=\"font-size:22px\">No les voy a mentir. Todav\u00eda me sorprende verlo contar el cuento con un caf\u00e9 en la mano y ri\u00e9ndose.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:22px\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/1-3.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4837\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/1-3.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/1-3.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/1-3.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/1-3.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/1-3.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>Mucha rabia y poca raz\u00f3n<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">Luego del regreso traum\u00e1tico de Julieth y sus acompa\u00f1antes, <a href=\"https:\/\/www.eltiempo.com\/colombia\/otras-ciudades\/la-agonizante-travesia-por-el-parque-los-nevados-que-termino-con-la-muerte-de-mi-novio-en-pleno-31-de-diciembre-adios-amor-3418604\" title=\"\">la figura del internet se despach\u00f3 <\/a>acusando a Parques Nacionales de no haber \u201cbrindado las herramientas y la asistencia\u201d. Tambi\u00e9n se quej\u00f3 de que un arriero que quiso auxiliar a Kevin con una inyecci\u00f3n de dexametasona, en sus palabras \u201cno ten\u00eda conocimiento de aplicar inyecciones\u201d y de una \u201cmala atenci\u00f3n recibida en la finca\u201d. Palabras que, entendemos, salieron en un momento de shock y frustraci\u00f3n por un viaje que no sali\u00f3 como esperaban y con consecuencias absolutamente tr\u00e1gicas. Incluso el <a href=\"https:\/\/www.elpais.com.co\/colombia\/hablo-papa-de-kevin-bocanegra-montanista-que-murio-en-el-nevado-del-tolima-mi-hija-vio-como-descendieron-el-cadaver-2924.html\" title=\"\">padre del fallecido, Hernando Bocanegra, se\u00f1al\u00f3 en el p\u00f3dcast \u2018M\u00e1s all\u00e1 del silencio\u2019<\/a> que \u201cNo tuvieron el apoyo ni de Defensa Civil, ni de Bomberos ni de ning\u00fan ente (&#8230;) Mi hija tuvo que ver la forma como descendieron el cad\u00e1ver de mi hijo de la parte alta, y no fue una cuesti\u00f3n humana porque se hizo en un caballo, se hizo sin ning\u00fan tipo de protocolo\u201d.<\/p>\n\n\n\n<p style=\"font-size:22px\">Sin embargo, ninguno de los acusados tiene ninguna responsabilidad. Empezando por los arrieros y las personas de las fincas que sirven como campamento previo al ascenso, los cuales no tienen por qu\u00e9 contar con la preparaci\u00f3n para atender estas emergencias; ellos simplemente son familias campesinas que cobran la estad\u00eda y la comida. De acuerdo con Miguel \u00c1ngel Mej\u00eda D\u00edaz, columnista de El Cuyabran Post y que incursion\u00f3 con unos socios en el tema del turismo de alta monta\u00f1a con su empresa Antis, \u201ctampoco se le puede pedir a Parques (una entidad encargada de administrar y gestionar ambientalmente un \u00e1rea protegida, y no de ofrecer turismo) que tengan funcionarios en \u00e1reas de 50 km<sup>2<\/sup> por cada uno, para hacerle seguimiento a todos los visitantes que ingresan. Pero adem\u00e1s suben las 24 horas e incluso de noche\u201d. El mismo jefe del parque Los Nevados, Sim\u00f3n Moreno, advirti\u00f3 en El Tiempo que Julieth, Kevin y compa\u00f1\u00eda \u201cindicaron que iban a tomar la ruta La Primavera \u2013 Termales \u2013 El Salto \u2013 Juntas. No indicaron que iban a cumbre\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/2-3.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4838\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/2-3.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/2-3.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/2-3.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/2-3.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/2-3.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">A\u00f1ade Miguel \u00c1ngel que hacer un rescate en alta monta\u00f1a es muy costoso y que es algo il\u00f3gico pensar en cargar esa responsabilidad en la alcald\u00eda de Salento, o en la de Ibagu\u00e9, \u201ccuando todo se debi\u00f3 a la falta de precauci\u00f3n de turistas y los operadores\u201d.<\/p>\n\n\n\n<p style=\"font-size:22px\">-Julieth cuenta que \u00d3scar, el gu\u00eda, les hab\u00eda prometido incluso rescate en helic\u00f3ptero\u2026<\/p>\n\n\n\n<p style=\"font-size:22px\">-S\u00ed, pero por persona les estaban cobrando un mill\u00f3n 300 mil pesos. Habr\u00eda que empezar a concientizar a la gente sobre este turismo de alto valor. Realmente llegar a una cumbre como la del nevado del Tolima no es econ\u00f3mico: si uno tiene en cuenta que el gu\u00eda debe ser profesional; que debe contar con certificaciones y cursos preparatorios de primeros auxilios, rescate de alta monta\u00f1a, ascenso y descenso de monta\u00f1a, y rescates verticales (algunos de los cuales se expiden en Cundinamarca y otros en Per\u00fa); que deben llevar medicamentos, radio, pipas de ox\u00edgeno, cuando la noche en La Primavera te la est\u00e1n cobrando a 40 o 50 mil pesos\u2026 pues son condiciones que superan por mucho el valor que se est\u00e1 pagando. Aparte de eso, es imposible hacer un rescate en helic\u00f3ptero por las condiciones del viento, no tiene donde aparcar, el precio, la disponibilidad del veh\u00edculo\u2026<\/p>\n\n\n\n<p style=\"font-size:22px\">Es decir, el gu\u00eda minti\u00f3. Pero no fue su \u00fanico pecado. Habiendo pasado por una experiencia muy cercana, Adri\u00e1n se\u00f1ala dos se\u00f1ales de alerta: \u201cUno tiene una capacidad de entender su grupo de caminata dependiendo de cu\u00e1nto se demora el primer d\u00eda. Ellos dicen que en la primera fecha llegaron de noche a La Primavera. Si un grupo se demora m\u00e1s de 10 o 12 horas en un recorrido que debi\u00f3 demorar 5 o 6 para personas experimentadas, me indica que la capacidad f\u00edsica no es buena\u201d. Subraya en segundo lugar, que es impensable que por un solo gu\u00eda vayan m\u00e1s de 3 personas. \u201cPorque necesitas, al hacer la cordada en el glacial, idealmente un puntero, alguien que vaya atr\u00e1s y m\u00e1ximo 3 en el medio: 5 personas m\u00e1ximo. No puedes hacer una cordada de 12\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/10-1.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4846\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/10-1.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/10-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/10-1.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/10-1.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/10-1.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">-Tendemos a creer que porque mucha gente est\u00e1 haciendo cumbre y el turismo de alta monta\u00f1a se est\u00e1 posicionando, no tiene riesgos o no se necesita preparaci\u00f3n, y ah\u00ed tenemos la primera equivocaci\u00f3n tanto los entes gubernamentales, las empresas de turismo, como las personas que contratan la aventura- reitera Miguel \u00c1ngel -Por el lado del usuario, aprender a conocer el cuerpo y el estado f\u00edsico. Todo el mundo lo puede intentar y a lo largo de los a\u00f1os me he dado cuenta que mucha gente que est\u00e1 muy preparada y puede haber hecho cumbre varias veces, y aun as\u00ed puede sufrir fracturas, ca\u00eddas, un mal de altura, que les impide llegar. Si eso es para los profesionales y los que viven de eso, qu\u00e9 nos espera a los que vamos como turistas. Ninguna empresa seria te garantiza cumbre\u2026 lo que se venden son intentos de cumbre, porque pueden pasar mil cosas que lo impidan por encima de la preparaci\u00f3n f\u00edsica de las personas y de tener en cuenta la mayor cantidad de variables.<\/p>\n\n\n\n<p style=\"font-size:22px\">-Adri\u00e1n cuenta que mientras esperaba a que lo ayudaran a evacuar hacia Salento subi\u00f3 un gu\u00eda con un grupo y sin radio. Me resulta entre curioso y preocupante\u2026<\/p>\n\n\n\n<p style=\"font-size:22px\">-Es muy preocupante. Hay elementos que no pueden faltar y uno es el radio, as\u00ed como uno esperar\u00eda que lleven GPS, botiqu\u00edn, cuerdas, linterna, mantas para guardar el calor en emergencias. Gracias a una acci\u00f3n de tutela que aplica en el parque Los Nevados y que tiene entutelado a medio pa\u00eds (r\u00ede), uno de los puntos identificados que se ten\u00edan que mejorar era el tema de la radiofrecuencia; es una zona boscosa de muy dif\u00edcil acceso y ha sido muy dif\u00edcil la comunicaci\u00f3n. Incluso tener conectado para hacer no solo el turismo sino para que las personas de Parques trabajen, para que las alcald\u00edas se comuniquen.<\/p>\n\n\n\n<p style=\"font-size:22px\">-Desde el punto de vista m\u00e9dico- le consulto a Sebasti\u00e1n- cu\u00e1l fue el punto de inflexi\u00f3n, el momento en el que, de haberse detenido y regresado, Kevin se hubiera salvado.<\/p>\n\n\n\n<p style=\"font-size:22px\">-La primera bandera roja fue contratar este gu\u00eda. Digamos que si soy la persona que vende el conocimiento y el entrenamiento, deber\u00eda tener muy presente un umbral de fen\u00f3menos que determinen cuando tomar la decisi\u00f3n de evacuar. Y para m\u00ed es cuando el cliente manifiesta un malestar, porque por lo general uno tolera s\u00edntomas breves y \u201ccome callado\u201d. Pero cuando se expresa p\u00fablicamente que no se siente bien, pasa de ser un problema personal a uno grupal, y esto s\u00ed que lo sabe la gente que sabe de gesti\u00f3n de desastres. La respuesta que recibi\u00f3 es que no fuera flojo, e incluso la idea era incrementar el peligro en la medida en la que avanzaban hacia la cima.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/8-1.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4844\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/8-1.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/8-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/8-1.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/8-1.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/8-1.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\"><strong>M\u00e1s all\u00e1 de la tragedia personal<\/strong><\/p>\n\n\n\n<p style=\"font-size:22px\">Y es que, pese a la dificultad, el riesgo, el costo y la log\u00edstica que subir al nevado implica, no se est\u00e1 controlando la carga de personas que est\u00e1n ingresando a este santuario. Miguel \u00c1ngel se\u00f1ala que en un solo d\u00eda puede haber 120 personas tratando de alcanzar la cumbre. \u201cNi la capacidad de carga de las casas (que son viviendas familiares), ni de los senderos, ni del p\u00e1ramo de Romerales, ni del p\u00e1ramo de La Virgen, ni de la laguna del Encanto est\u00e1n para eso\u201d.<\/p>\n\n\n\n<p style=\"font-size:22px\">Es decir, e incre\u00edblemente para algunos, los m\u00e1s afectados con la din\u00e1mica no son los visitantes, sino el entorno natural que representa el nevado. Esto, sumado a una especie de guerra de precios entre operadores (legales e informales) que buscan abaratar lo m\u00e1s posible las excursiones, est\u00e1 poniendo en riesgo el ecosistema estrat\u00e9gico del que (oh sorpresa) las personas tambi\u00e9n somos parte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/12.png?resize=1024%2C576\" alt=\"\" class=\"wp-image-4848\" srcset=\"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/12.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/12.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/12.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/12.png?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/12.png?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p style=\"font-size:22px\">-Hace poco le\u00ed un art\u00edculo en un blog diciendo que en el Everest estaban intentando subir ostensiblemente los precios porque adem\u00e1s de los costos econ\u00f3micos, los ambientales eran demasiado altos- a\u00f1ade Mej\u00eda -Eso nos est\u00e1 pasando. Y ojo, que soy de los que piensa que todos tenemos derecho a disfrutar de la naturaleza; soy del eslogan de que hay que conocer para proteger, porque si no sabemos de la belleza que tenemos es muy dif\u00edcil sentir apropiaci\u00f3n por ella. Sin embargo, cuando se hace de manera tan desproporcionada y superando la capacidad de carga, nos estamos metiendo un tiro en el pie.<\/p>\n\n\n\n<p style=\"font-size:22px\">Somos conscientes que el tema resulta extremadamente complejo. Pero aun teniendo que cumplirle al Consejo de Estado con los compromisos que buscan darle respuesta al <a href=\"https:\/\/elcuyabranpost.com\/index.php\/2024\/03\/23\/una-alerta-dura-y-una-solucion-blandita-frente-a-la-extincion-del-parque-de-los-nevados\/\" title=\"\">fallo de segunda instancia expedido por el Tribunal Superior del Distrito Judicial de Ibagu\u00e9<\/a> (la tutela antes mencionada) y que reconoce el parque de Los Nevados como sujeto de derechos, todav\u00eda nos llegan noticias como <a href=\"https:\/\/vozdelpueblo920am.com\/index.php\/2025\/02\/01\/gobernacion-del-tolima-y-la-presidencia-de-la-republica-habrian-incumplido-medidas-ambientales-en-el-parque-natural-de-los-nevados\/\" title=\"\">la publicada por el medio La Voz del Pueblo el 1 de febrero<\/a>, que se\u00f1ala que tanto la Gobernaci\u00f3n del Tolima como la Presidencia de la Rep\u00fablica habr\u00edan incumplido las medidas ambientales pactadas y a su cargo. Ah\u00ed les abrieron incidente de desacato por permitir que la v\u00eda entre Murillo y Manizales se llenara de autom\u00f3viles, pas\u00e1ndose por la galleta el pico y placa ambiental. Eso nos lleva a pensar\u2026<\/p>\n\n\n\n<p style=\"font-size:22px\">\u00bfSeremos as\u00ed de brutos? \u00bfReally? Por lo menos hasta que nos estalle la papa en la cara\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Andr\u00e9s Mej\u00eda &#8211; Sebasti\u00e1n Ruiz &#8211; Miguel \u00c1ngel Mej\u00eda La mayor\u00eda de las veces, el tomar una decisi\u00f3n por encima de otra no origina diferencias dr\u00e1sticas. Pero en ambientes hostiles, que exigen al cuerpo a rendir en condiciones extremas, una disyuntiva puede sostener o cegar una vida. Tom\u00e1ndose un caf\u00e9 mientras me cuenta su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16],"tags":[552,553,551,15,554,213],"class_list":["post-4836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elpostreporta","tag-fallecimiento","tag-montanismo","tag-nevado-del-tolima","tag-quindio","tag-salento","tag-turismo"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elcuyabranpost.com\/wp-content\/uploads\/2025\/02\/3-3.png?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts\/4836"}],"collection":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/comments?post=4836"}],"version-history":[{"count":6,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts\/4836\/revisions"}],"predecessor-version":[{"id":4894,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/posts\/4836\/revisions\/4894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/media\/4839"}],"wp:attachment":[{"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/media?parent=4836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/categories?post=4836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcuyabranpost.com\/index.php\/wp-json\/wp\/v2\/tags?post=4836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}